{"id":551,"date":"2024-03-26T04:40:51","date_gmt":"2024-03-26T04:40:51","guid":{"rendered":"https:\/\/www.ciputra.ac.id\/konaikom\/?page_id=551"},"modified":"2024-04-02T20:25:20","modified_gmt":"2024-04-02T20:25:20","slug":"faq","status":"publish","type":"page","link":"https:\/\/www.ciputra.ac.id\/konaikom\/faq\/","title":{"rendered":"FAQ"},"content":{"rendered":"\n<div class=\"wp-block-cover alignfull\" style=\"padding-top:5%;padding-right:4.5%;padding-bottom:5%;padding-left:4.5%\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-60 has-background-dim\" style=\"background-color:#614426\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1707\" class=\"wp-block-cover__image-background wp-image-581\" alt=\"\" src=\"https:\/\/www.ciputra.ac.id\/konaikom\/wp-content\/uploads\/2024\/03\/IMG_0080-scaled.jpg\" style=\"object-position:53% 72%\" data-object-fit=\"cover\" data-object-position=\"53% 72%\" srcset=\"https:\/\/www.ciputra.ac.id\/konaikom\/wp-content\/uploads\/2024\/03\/IMG_0080-scaled.jpg 2560w, https:\/\/www.ciputra.ac.id\/konaikom\/wp-content\/uploads\/2024\/03\/IMG_0080-300x200.jpg 300w, https:\/\/www.ciputra.ac.id\/konaikom\/wp-content\/uploads\/2024\/03\/IMG_0080-1024x683.jpg 1024w, https:\/\/www.ciputra.ac.id\/konaikom\/wp-content\/uploads\/2024\/03\/IMG_0080-768x512.jpg 768w, https:\/\/www.ciputra.ac.id\/konaikom\/wp-content\/uploads\/2024\/03\/IMG_0080-1536x1024.jpg 1536w, https:\/\/www.ciputra.ac.id\/konaikom\/wp-content\/uploads\/2024\/03\/IMG_0080-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><div class=\"wp-block-cover__inner-container has-global-padding is-layout-constrained wp-container-core-cover-is-layout-0940a840 wp-block-cover-is-layout-constrained\">\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center has-text-color has-link-color has-kollektif-bold-font-family wp-elements-c2ed781a540d306f4714de68f5f305b9\" style=\"color:#fffcfa;font-size:4rem;text-transform:uppercase\">Frequently Asked Question<\/h2>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-background has-global-padding is-layout-constrained wp-container-core-group-is-layout-913786d1 wp-block-group-is-layout-constrained\" style=\"background-color:#fffffd;margin-top:0;margin-bottom:0;padding-top:5%;padding-right:10%;padding-bottom:5%;padding-left:10%\">\n<div class=\"wp-block-aab-group-accordion aagb_accordion_019e7a4e-3536-459f-b954-0a097e180e3e\">\n<div class=\"wp-block-aab-accordion-item aagb__accordion_container\" style=\"border:1px undefined undefined;margin-top:0px;margin-bottom:15px;border-radius:0px\"><div class=\"aagb__accordion_head aagb_right_icon\" data-active=\"false\" style=\"color:#2f1e18;background-color:#eac6a4;padding:10px 18px 10px 18px\"><div class=\"aagb__accordion_heading aagb_right_icon\"><h4 class=\"aagb__accordion_title\" style=\"margin:0;color:#2f1e18\">Apa luaran yang Saya dapatkan setelah mengikuti KONAIKOM?<\/h4><\/div><div class=\"aagb__accordion_icon\" style=\"color:#2f1e18;background-color:transparent\"><span class=\"aagb__icon dashicons dashicons-plus-alt2\"><\/span><\/div><\/div><div class=\"aagb__accordion_body \" role=\"region\" style=\"background-color:#fffcfa;border-top:1px undefined undefined;padding:10px 18px 10px 18px\">\n<p class=\"has-text-color has-link-color has-asap-condensed-medium-font-family wp-elements-d57799c8f58455368614880475aa1981\" style=\"color:#614426;font-size:1.2rem\">Semua paper yang lolos akan masuk ke dalam Prosiding \/ Book Chapter ber-ISBN. Paper yang terpilih dapat masuk kedalam Jurnal Nasional\/ Terakreditasi.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-aab-accordion-item aagb__accordion_container\" style=\"border:1px solid #cccccc;margin-top:0px;margin-bottom:15px;border-radius:0px\"><div class=\"aagb__accordion_head aagb_right_icon\" data-active=\"false\" style=\"color:#2f1e18;background-color:#eac6a4;padding:10px 18px 10px 18px\"><div class=\"aagb__accordion_heading aagb_right_icon\"><h4 class=\"aagb__accordion_title\" style=\"margin:0;color:#2f1e18\">Apa boleh Saya memakai bahasa Inggris dalam naskah Saya?<\/h4><\/div><div class=\"aagb__accordion_icon\" style=\"color:#2f1e18;background-color:transparent\"><span class=\"aagb__icon dashicons dashicons-plus-alt2\"><\/span><\/div><\/div><div class=\"aagb__accordion_body \" role=\"region\" style=\"background-color:#fffcfa;border-top:1px solid #cccccc;padding:10px 18px 10px 18px\">\n<p class=\"has-text-color has-link-color has-asap-condensed-medium-font-family wp-elements-bbc5f5a63e2bdf94155086126e737d60\" style=\"color:#614426;font-size:1.2rem\">Bahasa pengantar boleh dalam bahasa Indonesia atau Inggris.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-aab-accordion-item aagb__accordion_container\" style=\"border:1px undefined undefined;margin-top:0px;margin-bottom:15px;border-radius:0px\"><div class=\"aagb__accordion_head aagb_right_icon\" data-active=\"false\" style=\"color:#2f1e18;background-color:#eac6a4;padding:10px 18px 10px 18px\"><div class=\"aagb__accordion_heading aagb_right_icon\"><h4 class=\"aagb__accordion_title\" style=\"margin:0;color:#2f1e18\">Apakah Saya bisa mendaftar early bird dan mengumpulkan naskah menyusul?<\/h4><\/div><div class=\"aagb__accordion_icon\" style=\"color:#2f1e18;background-color:transparent\"><span class=\"aagb__icon dashicons dashicons-plus-alt2\"><\/span><\/div><\/div><div class=\"aagb__accordion_body \" role=\"region\" style=\"background-color:#fffcfa;border-top:1px undefined undefined;padding:10px 18px 10px 18px\">\n<p class=\"has-text-color has-link-color has-asap-condensed-medium-font-family wp-elements-6fb15d628bc539add4f5e63fb678aef1\" style=\"color:#614426;font-size:1.2rem\">Tidak bisa. Peserta wajib mengirimkan naskah saat pendaftaran. Pendaftaran akan dibuka sampah tanggal 19 Mei 2024.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-aab-accordion-item aagb__accordion_container\" style=\"border:1px solid #cccccc;margin-top:0px;margin-bottom:15px;border-radius:0px\"><div class=\"aagb__accordion_head aagb_right_icon\" data-active=\"false\" style=\"color:#2f1e18;background-color:#eac6a4;padding:10px 15px 10px 15px\"><div class=\"aagb__accordion_heading aagb_right_icon\"><h4 class=\"aagb__accordion_title\" style=\"margin:0;color:#2f1e18\">Apabila paper Saya diterima, apakah Saya wajib hadir di Universitas Ciputra untuk presentasi?<\/h4><\/div><div class=\"aagb__accordion_icon\" style=\"color:#2f1e18;background-color:transparent\"><span class=\"aagb__icon dashicons dashicons-plus-alt2\"><\/span><\/div><\/div><div class=\"aagb__accordion_body \" role=\"region\" style=\"background-color:#fffcfa;border-top:1px solid #cccccc;padding:10px 15px 10px 15px\">\n<p class=\"has-text-color has-link-color has-asap-condensed-medium-font-family wp-elements-07dd6eef9836c5eaf6709460e8d9205a\" style=\"color:#614426;font-size:1.2rem\">Peserta memiliki pilihan untuk melakukan presentasi secara offline atau online. Presentasi secara online dilakukan dengan mengirimkan video presentasi sesuai dengan syarat dan ketentuan yang berlaku.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-aab-accordion-item aagb__accordion_container\" style=\"border:1px solid #cccccc;margin-top:0px;margin-bottom:15px;border-radius:0px\"><div class=\"aagb__accordion_head aagb_right_icon\" data-active=\"false\" style=\"color:#2f1e18;background-color:#eac6a4;padding:10px 15px 10px 15px\"><div class=\"aagb__accordion_heading aagb_right_icon\"><h4 class=\"aagb__accordion_title\" style=\"margin:0;color:#2f1e18\">Bagaimana Saya bisa tahu paper Saya diterima?<\/h4><\/div><div class=\"aagb__accordion_icon\" style=\"color:#2f1e18;background-color:transparent\"><span class=\"aagb__icon dashicons dashicons-plus-alt2\"><\/span><\/div><\/div><div class=\"aagb__accordion_body \" role=\"region\" style=\"background-color:#fffcfa;border-top:1px solid #cccccc;padding:10px 15px 10px 15px\">\n<p class=\"has-text-color has-link-color has-asap-condensed-medium-font-family wp-elements-9568449317bfce419fdaf1a49afe7d1c\" style=\"color:#614426;font-size:1.2rem\">Anda akan menerima email konfirmasi penerimaandari KONAIKOM setelah naskah Anda diterima. Pengumuman maksimal 2 minggu setelah pengumpulan naskah.<\/p>\n<\/div><\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-551","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.ciputra.ac.id\/konaikom\/wp-json\/wp\/v2\/pages\/551","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ciputra.ac.id\/konaikom\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ciputra.ac.id\/konaikom\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ciputra.ac.id\/konaikom\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ciputra.ac.id\/konaikom\/wp-json\/wp\/v2\/comments?post=551"}],"version-history":[{"count":12,"href":"https:\/\/www.ciputra.ac.id\/konaikom\/wp-json\/wp\/v2\/pages\/551\/revisions"}],"predecessor-version":[{"id":759,"href":"https:\/\/www.ciputra.ac.id\/konaikom\/wp-json\/wp\/v2\/pages\/551\/revisions\/759"}],"wp:attachment":[{"href":"https:\/\/www.ciputra.ac.id\/konaikom\/wp-json\/wp\/v2\/media?parent=551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}